{"id":3472,"date":"2018-04-01T17:59:23","date_gmt":"2018-04-01T16:59:23","guid":{"rendered":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024.jpg"},"modified":"2018-04-01T18:48:12","modified_gmt":"2018-04-01T17:48:12","slug":"ruine_haichenbach_kerschbaumer-schloessl_024","status":"inherit","type":"attachment","link":"http:\/\/www.burgenkunde.at\/wordpress\/ruine_haichenbach_kerschbaumer-schloessl_024\/","title":{"rendered":"Ruine Haichenbach &#8211; Kerschbaumer-Schloessl"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false,"ngg_post_thumbnail":0},"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href=\"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024.jpg\" rel=\"lightbox[3472]\"><img width=\"300\" height=\"200\" src=\"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"Ruine Haichenbach - Kerschbaumer-Schloessl\" loading=\"lazy\" srcset=\"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-300x200.jpg 300w, http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-768x512.jpg 768w, http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-1024x683.jpg 1024w, http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\"><\/a><\/p>\n<p>Am Fu&szlig;e des Turmes sind zwei unterschiedliche Gesteinsarten im Mauerwerk erkennbar.<\/p>\n"},"caption":{"rendered":"<p>Am Fu\u00dfe des Turmes sind zwei unterschiedliche Gesteinsarten im Mauerwerk erkennbar.<\/p>\n"},"alt_text":"Ruine Haichenbach - Kerschbaumer-Schloessl","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":800,"file":"2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024.jpg","sizes":{"thumbnail":{"file":"Ruine_Haichenbach_Kerschbaumer-Schloessl_024-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-150x150.jpg"},"medium":{"file":"Ruine_Haichenbach_Kerschbaumer-Schloessl_024-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-300x200.jpg"},"medium_large":{"file":"Ruine_Haichenbach_Kerschbaumer-Schloessl_024-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-768x512.jpg"},"large":{"file":"Ruine_Haichenbach_Kerschbaumer-Schloessl_024-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-1024x683.jpg"},"featured":{"file":"Ruine_Haichenbach_Kerschbaumer-Schloessl_024-670x300.jpg","width":670,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-670x300.jpg"},"featured-medium":{"file":"Ruine_Haichenbach_Kerschbaumer-Schloessl_024-230x230.jpg","width":230,"height":230,"mime_type":"image\/jpeg","source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-230x230.jpg"},"slider":{"file":"Ruine_Haichenbach_Kerschbaumer-Schloessl_024-1018x460.jpg","width":1018,"height":460,"mime_type":"image\/jpeg","source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-1018x460.jpg"},"gallery":{"file":"Ruine_Haichenbach_Kerschbaumer-Schloessl_024-474x342.jpg","width":474,"height":342,"mime_type":"image\/jpeg","source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024-474x342.jpg"},"full":{"file":"Ruine_Haichenbach_Kerschbaumer-Schloessl_024.jpg","width":1200,"height":800,"mime_type":"image\/jpeg","source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"http:\/\/www.burgenkunde.at\/wordpress\/wp-content\/uploads\/2018\/04\/Ruine_Haichenbach_Kerschbaumer-Schloessl_024.jpg","_links":{"self":[{"href":"http:\/\/www.burgenkunde.at\/wordpress\/wp-json\/wp\/v2\/media\/3472"}],"collection":[{"href":"http:\/\/www.burgenkunde.at\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.burgenkunde.at\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.burgenkunde.at\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.burgenkunde.at\/wordpress\/wp-json\/wp\/v2\/comments?post=3472"}]}}